{"id":11572,"date":"2026-05-24T00:38:23","date_gmt":"2026-05-23T22:38:23","guid":{"rendered":"https:\/\/www.apuestasbono.com\/pe\/?p=11572"},"modified":"2026-06-11T00:21:59","modified_gmt":"2026-06-11T05:21:59","slug":"copa-mundial-2026-calendario-grupos-apuestas","status":"publish","type":"post","link":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/","title":{"rendered":"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas"},"content":{"rendered":"<p><span style=\"font-weight: 400\">El Mundial 2026 est\u00e1 a la vuelta de la esquina: el partido inaugural se disputar\u00e1 en el Estadio Azteca de Ciudad de M\u00e9xico el 11 de junio, cuando M\u00e9xico reciba a Sud\u00e1frica. Adem\u00e1s, se trata de la esperada Copa Mundial 2026, que contar\u00e1 con otros 102 partidos en M\u00e9xico, Canad\u00e1 y Estados Unidos antes de que la final tenga lugar el 7 de julio en el <a href=\"https:\/\/es.wikipedia.org\/wiki\/MetLife_Stadium\">MetLife Stadium<\/a> de Nueva Jersey.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En<\/span><a href=\"https:\/\/www.apuestasbono.com\/pe\/\"> <span style=\"font-weight: 400\">Apuestasbono.com<\/span><\/a><span style=\"font-weight: 400\">, queremos ayudarte a estar lo m\u00e1s preparado posible para El Mundial 2026. Esperamos ofrecerte la mejor informaci\u00f3n para tus apuestas del torneo mundialista. Esta p\u00e1gina ser\u00e1 tu centro de referencia donde podr\u00e1s revisar toda la cobertura previa a la Copa del Mundo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aqu\u00ed encontrar\u00e1s todas nuestras gu\u00edas de equipos: 48 en total. Tambi\u00e9n puedes revisar nuestras 12 gu\u00edas de grupos disponibles y nuestro calendario descargable. Todo esto junto a noticias y mucho contenido que ofreceremos, para que te prepares antes de que arranque la gran competici\u00f3n de la Copa Mundial 2026.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12362 size-full\" src=\"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-Mundial-2026.jpg\" alt=\"Trofeo de la Copa Mundial 2026\" width=\"1016\" height=\"677\" srcset=\"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-Mundial-2026.jpg 1016w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-Mundial-2026-300x200.jpg 300w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-Mundial-2026-768x512.jpg 768w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-Mundial-2026-95x63.jpg 95w\" sizes=\"auto, (max-width: 1016px) 100vw, 1016px\" \/><\/p>\n<p style=\"text-align: center\"><em>Trofeo de la Copa Mundial 2026.<\/em><\/p>\n<h2><b>Descubre nuestros art\u00edculos:<\/b><\/h2>\n<ul>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-de-la-fifa-2026-guia-apuestas-11694\/\"><span style=\"font-weight: 400\">Gu\u00eda de apuestas para la Copa del Mundo 2026<\/span><\/a><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/5-tendencias-historicas-de-apuestas-en-el-mundial-11799\/\"><span style=\"font-weight: 400\">5 tendencias hist\u00f3ricas de apuestas en la Copa del Mundo: y lo que nos dicen<\/span><\/a><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/calendario_copa_mundial_2026-2.xlsx\"><span style=\"font-weight: 400\">Descarga el calendario<\/span><\/a><\/li>\n<\/ul>\n<h2><b>Nuestras gu\u00edas de grupos del Mundial 2026:<\/b><\/h2>\n<p>A continuaci\u00f3n, descubre todo lo que debes saber de los grupos que componen las 48 selecciones\u00a0 mundialistas en la competencia Copa Mundial 2026. Estos son: Este a\u00f1o, la Copa Mundial 2026 re\u00fane selecciones de todo el mundo en una competencia sin igual.<\/p>\n\n<table id=\"tablepress-272\" class=\"tablepress tablepress-id-272 tabla-grupos\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-a-mundial-2026-12333\/\">Grupo A<\/a><\/th><th class=\"column-2\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-b-mundial-2026-12556\/\">Grupo B<\/a><\/th><th class=\"column-3\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-c-mundial-2026-12564\/\">Grupo C<\/a><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-d-mundial-2026-12399\/\">Grupo D<\/a><\/td><td class=\"column-2\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-e-mundial-2026-12006\/\">Grupo E<\/a><\/td><td class=\"column-3\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-f-mundial-2026-12787\/\">Grupo F<\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-g-mundial-2026-12026\/\">Grupo G<\/a><\/td><td class=\"column-2\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-h-mundial-2026-12409\/\">Grupo H<\/a><\/td><td class=\"column-3\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-del-grupo-i-del-mundial-2026-13109\/\">Grupo I<\/a><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-j-mundial-2026-12757\/\">Grupo J<\/a><\/td><td class=\"column-2\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-grupo-k-mundial-2026-12131\/\">Grupo K<\/a><\/td><td class=\"column-3\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/grupo-l-mundial-2026-11809\/\">Grupo L<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-272 from cache -->\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12363 size-full\" src=\"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Grupos-de-la-Copa-Mundial-2026.jpg\" alt=\"Grupos de la Copa Mundial 2026\" width=\"1139\" height=\"760\" srcset=\"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Grupos-de-la-Copa-Mundial-2026.jpg 1139w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Grupos-de-la-Copa-Mundial-2026-300x200.jpg 300w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Grupos-de-la-Copa-Mundial-2026-1024x683.jpg 1024w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Grupos-de-la-Copa-Mundial-2026-768x512.jpg 768w, https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Grupos-de-la-Copa-Mundial-2026-95x63.jpg 95w\" sizes=\"auto, (max-width: 1139px) 100vw, 1139px\" \/><\/h3>\n<p>&nbsp;<\/p>\n<h2>Revisa nuestras gu\u00edas de equipos de la Copa Mundial 2026<\/h2>\n<h3 data-section-id=\"1280s2b\" data-start=\"303\" data-end=\"343\">Selecciones UEFA &#8211; Mundial 2026<\/h3>\n<p data-start=\"345\" data-end=\"531\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-alemania-mundial-2026-11821\/\">Alemania<\/a><br data-start=\"353\" data-end=\"356\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-de-austria-para-el-mundial-2026-11846\/\">Austria<\/a><br data-start=\"363\" data-end=\"366\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-belgica-mundial-2026-11876\/\">B\u00e9lgica<\/a><br data-start=\"373\" data-end=\"376\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-bosnia-herzegovina-mundial-2026-12153\/\">Bosnia y Herzegovina<\/a><br data-start=\"396\" data-end=\"399\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-croacia-mundial-2026-11779\/\">Croacia<\/a><br data-start=\"406\" data-end=\"409\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-de-escocia-para-el-mundial-2026-12018\/\">Escocia<\/a><br data-start=\"416\" data-end=\"419\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-espana-mundial-2026-11917\/\">Espa\u00f1a<\/a><br data-start=\"425\" data-end=\"428\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-francia-mundial-2026-12639\/\">Francia<\/a><br data-start=\"435\" data-end=\"438\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-inglaterra-mundial-2026-11769\/\">Inglaterra<\/a><br data-start=\"448\" data-end=\"451\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-noruega-mundial-2026-12726\/\">Noruega<\/a><br data-start=\"458\" data-end=\"461\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-paises-bajos-mundial-2026-12504\/\">Pa\u00edses Bajos<\/a><br data-start=\"473\" data-end=\"476\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-portugal-mundial-2026-12040\/\">Portugal<\/a><br data-start=\"484\" data-end=\"487\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-republica-checa-mundial-2026-12345\/\">Rep\u00fablica Checa<\/a><br data-start=\"502\" data-end=\"505\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-suecia-mundial-2026-12629\/\">Suecia<\/a><br data-start=\"511\" data-end=\"514\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-suiza-mundial-2026-12145\/\">Suiza<\/a><br data-start=\"519\" data-end=\"522\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-turquia-mundial-2026-12653\/\">Turqu\u00eda<\/a><\/p>\n<h3 data-section-id=\"e5aacd\" data-start=\"538\" data-end=\"591\">Equipos Conmebol<\/h3>\n<p data-start=\"593\" data-end=\"655\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-argentina-mundial-2026-12368\/\">Argentina<\/a><br data-start=\"602\" data-end=\"605\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-brasil-mundial-2026-11982\/\">Brasil<\/a><br data-start=\"611\" data-end=\"614\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-colombia-mundial-2026-12032\/\">Colombia<\/a><br data-start=\"622\" data-end=\"625\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-ecuador-mundial-2026-12425\/\">Ecuador<\/a><br data-start=\"632\" data-end=\"635\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-paraguay-mundial-2026-12589\/\">Paraguay<\/a><br data-start=\"643\" data-end=\"646\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-uruguay-mundial-2026-12455\/\">Uruguay<\/a><\/p>\n<h3 data-section-id=\"je2ndz\" data-start=\"662\" data-end=\"710\">Selecciones CAF<\/h3>\n<p data-start=\"712\" data-end=\"845\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-argelia-mundial-2026-12376\/\">Argelia<\/a><br data-start=\"719\" data-end=\"722\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-cabo-verde-mundial-2026-12465\/\">Cabo Verde<\/a><br data-start=\"732\" data-end=\"735\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-costa-marfil-mundial-2026-11857\/\">Costa de Marfil<\/a><br data-start=\"750\" data-end=\"753\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-egipto-mundial-2026-11925\/\">Egipto<\/a><br data-start=\"759\" data-end=\"762\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-ghana-mundial-2026-11933\/\">Ghana<\/a><br data-start=\"767\" data-end=\"770\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-marruecos-mundial-2026-12092\/\">Marruecos<\/a><br data-start=\"779\" data-end=\"782\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-republica-democratica-congo-mundial-2026-12071\/\">Rep\u00fablica Democr\u00e1tica del Congo<\/a><br data-start=\"813\" data-end=\"816\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-senegal-mundial-2026-12716\/\">Senegal<\/a><br data-start=\"823\" data-end=\"826\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-sudafrica-mundial-2026-12290\/\">Sud\u00e1frica<\/a><br data-start=\"835\" data-end=\"838\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-tunez-mundial-2026-12137\/\">T\u00fanez<\/a><\/p>\n<h3 data-section-id=\"152rhd4\" data-start=\"852\" data-end=\"898\">Pa\u00edses de AFC<\/h3>\n<p data-start=\"900\" data-end=\"984\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-arabia-saudi-mundial-2026-12577\/\">Arabia Saud\u00ed<\/a><br \/>\n<a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-australia-mundial-2026-12481\/\">Australia<\/a><br data-start=\"912\" data-end=\"915\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-corea-del-sur-mundial-2026-12310\/\">Corea del Sur<\/a><br data-start=\"928\" data-end=\"931\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-irak-mundial-2026-12663\/\">Irak<\/a><br data-start=\"935\" data-end=\"938\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-iran-mundial-2026-12436\/\">Ir\u00e1n<\/a><br data-start=\"942\" data-end=\"945\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-japon-mundial-2026-12494\/\">Jap\u00f3n<\/a><br data-start=\"950\" data-end=\"953\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-jordania-mundial-2026-12386\/\">Jordania<\/a><br data-start=\"961\" data-end=\"964\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-catar-mundial-2026-12241\/\">Catar<\/a><br data-start=\"969\" data-end=\"972\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-uzbekistan-mundial-2026-12084\/\">Uzbekist\u00e1n<\/a><\/p>\n<h3 data-section-id=\"zkeo2b\" data-start=\"991\" data-end=\"1036\">Selecciones de Concacaf<\/h3>\n<p data-start=\"1038\" data-end=\"1099\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-canada-mundial-2026-12260\/\">Canad\u00e1<\/a><br data-start=\"1044\" data-end=\"1047\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-curazao-mundial-2026-11838\/\">Curazao<\/a><br data-start=\"1054\" data-end=\"1057\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-estados-unidos-mundial-2026-12124\/\">Estados Unidos<\/a><br data-start=\"1071\" data-end=\"1074\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-haiti-mundial-2026-12116\/\">Hait\u00ed<\/a><br data-start=\"1079\" data-end=\"1082\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-mexico-mundial-2026-12514\/\">M\u00e9xico<\/a><br data-start=\"1088\" data-end=\"1091\" \/><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-panama-mundial-2026-11974\/\">Panam\u00e1<\/a><\/p>\n<h3 data-section-id=\"19il2lt\" data-start=\"1106\" data-end=\"1148\">Selecci\u00f3n OFC &#8211; Mundial 2026<\/h3>\n<p data-section-id=\"19il2lt\" data-start=\"1106\" data-end=\"1148\"><a href=\"https:\/\/www.apuestasbono.com\/pe\/guia-nueva-zelanda-mundial-2026-11884\/\">Nueva Zelanda<\/a><\/p>\n<p>En Apuestasbono.com encontrar\u00e1s noticias, estad\u00edsticas, calendario, an\u00e1lisis y las mejores gu\u00edas para seguir cada partido celebrado en la Copa Mundial 2026 de la FIFA.<\/p>\n<h3>Noticias del Mundial 2026<\/h3>\n<ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-una-marea-albiceleste-de-mas-de-100-mil-personas-12919\/\">Copa Mundial: una marea albiceleste de m\u00e1s de 100 mil personas<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/neymar-regresa-a-brasil-y-desata-la-ilusion-del-mundial-2026-12873\/\"><span style=\"font-weight: 400\">Neymar regresa a Brasil y desata la ilusi\u00f3n del Mundial 2026<\/span><\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/argentina-en-el-mundial-fifa-2026-cuando-el-campeon-tambien-cayo-12996\/\">Argentina en el Mundial FIFA 2026: cuando el campe\u00f3n tambi\u00e9n cay\u00f3<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/mexico-en-el-mundial-de-futbol-del-fracaso-al-mundial-2026-12972\/\">M\u00e9xico en el Mundial de F\u00fatbol: del fracaso al Mundial 2026<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/uruguay-en-el-campeonato-mundial-de-futbol-2026-gloria-eterna-y-derrotas-imborrables-12990\/\">Uruguay en el Campeonato Mundial de F\u00fatbol 2026: gloria eterna y derrotas imborrables<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/brasil-en-la-copa-del-mundo-2026-del-maracanazo-a-la-humillacion-del-7-1-12999\/\">Brasil en la Copa del Mundo 2026: del Maracanazo a la humillaci\u00f3n del 7-1<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/colombia-en-el-mundial-2026-recuerdo-de-la-copa-que-nunca-se-hizo-12979\/\">Colombia en el Mundial 2026: Recuerdo de la Copa que nunca se hizo<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/la-celeste-llega-a-la-copa-del-mundo-2026-sin-la-confianza-de-la-hinchada-charrua-12168\/\">La Celeste llega a la Copa del Mundo 2026 sin la confianza de la hinchada charr\u00faa<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/el-feliz-regreso-de-paraguay-al-mundial-de-futbol-2026-12256\/\">El feliz regreso de Paraguay al Mundial de F\u00fatbol 2026<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/ecuador-rompe-todos-los-pronosticos-y-se-ilusiona-con-el-mundial-fifa-2026-12237\/\">Ecuador rompe todos los pron\u00f3sticos y se ilusiona con el Mundial FIFA 2026<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/mexico-apuesta-a-su-gente-en-la-copa-del-mundo-12475\/\">M\u00e9xico apuesta a su gente en la Copa del Mundo<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/colombia-vs-portugal-locura-mundial-por-este-partido-12712\/\">Colombia vs Portugal: Locura Mundial por este partido<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/paraguay-en-la-copa-mundial-de-futbol-12926\/\">Paraguay en la Copa Mundial de F\u00fatbol y la marca de una final sin victorias<\/a><\/li>\n<li><a href=\"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-las-heridas-historicas-que-marcan-a-ecuador-12952\/\">Copa Mundial 2026: las heridas hist\u00f3ricas que marcan a Ecuador <\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Mundial 2026 est\u00e1 a la vuelta de la esquina: el partido inaugural se disputar\u00e1 en el Estadio Azteca de Ciudad de M\u00e9xico el 11 de junio, cuando M\u00e9xico reciba a Sud\u00e1frica. Adem\u00e1s, se trata de la esperada Copa Mundial 2026, que contar\u00e1 con otros 102 partidos en M\u00e9xico, Canad\u00e1 y Estados Unidos antes de&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11574,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[578],"class_list":["post-11572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-copa-del-mundo-2026","leagues-copa-mundial-2026","teams-canada","teams-estados-unidos","teams-mexico","sports-futbol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Copa Mundial 2026- Apuestas Bono Per\u00fa<\/title>\n<meta name=\"description\" content=\"Ent\u00e9rate de todo sobre la Copa Mundial 2026: gu\u00edas de selecciones, grupos, calendario, noticias e informaci\u00f3n para tus apuestas deportivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas\" \/>\n<meta property=\"og:description\" content=\"Ent\u00e9rate de todo sobre la Copa Mundial 2026: gu\u00edas de selecciones, grupos, calendario, noticias e informaci\u00f3n para tus apuestas deportivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/\" \/>\n<meta property=\"og:site_name\" content=\"Apuestas Bono Per\u00fa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61561475662418\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-23T22:38:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T05:21:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-del-Mundo-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Nikolaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nikolaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/\"},\"author\":{\"name\":\"Nikolaj\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#\\\/schema\\\/person\\\/a7e418560e8162066d2bc2ebccafc84d\"},\"headline\":\"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas\",\"datePublished\":\"2026-05-23T22:38:23+00:00\",\"dateModified\":\"2026-06-11T05:21:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/\"},\"wordCount\":576,\"publisher\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/Trofeo-de-la-Copa-del-Mundo-scaled.webp\",\"keywords\":[\"Copa del Mundo 2026\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es-PE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/\",\"name\":\"Copa Mundial 2026- Apuestas Bono Per\u00fa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/Trofeo-de-la-Copa-del-Mundo-scaled.webp\",\"datePublished\":\"2026-05-23T22:38:23+00:00\",\"dateModified\":\"2026-06-11T05:21:59+00:00\",\"description\":\"Ent\u00e9rate de todo sobre la Copa Mundial 2026: gu\u00edas de selecciones, grupos, calendario, noticias e informaci\u00f3n para tus apuestas deportivas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/Trofeo-de-la-Copa-del-Mundo-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/Trofeo-de-la-Copa-del-Mundo-scaled.webp\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/copa-mundial-2026-calendario-grupos-apuestas-11572\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#website\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/\",\"name\":\"Apuestas Bono Per\u00fa\",\"description\":\"Portal de apuestas deportivas en Per\u00fa con pron\u00f3sticos diarios, an\u00e1lisis de partidos, cuotas actualizadas y comparativas de operadores.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#organization\",\"name\":\"Apuestas Bono Per\u00fa\",\"alternateName\":\"ApuestasBono Per\u00fa\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/ApuestasBono-Icono.png\",\"contentUrl\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/ApuestasBono-Icono.png\",\"width\":512,\"height\":512,\"caption\":\"Apuestas Bono Per\u00fa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61561475662418\",\"https:\\\/\\\/www.instagram.com\\\/apuestasbono?igsh=MTg3MTFyajVnbXBsZw==\"],\"description\":\"Portal de apuestas deportivas en Per\u00fa con pron\u00f3sticos diarios, an\u00e1lisis de partidos, cuotas actualizadas y comparativas de operadores.\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/#\\\/schema\\\/person\\\/a7e418560e8162066d2bc2ebccafc84d\",\"name\":\"Nikolaj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/www.apuestasbono.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Nikolaj-Juul-Nielsen-96x96.jpg\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Nikolaj-Juul-Nielsen-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.apuestasbono.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Nikolaj-Juul-Nielsen-96x96.jpg\",\"caption\":\"Nikolaj\"},\"description\":\"\u201cNiko\u201d es de Dinamarca y ha trabajado profesionalmente en el sector de las apuestas deportivas durante m\u00e1s de 25 a\u00f1os. Ha ejercido tanto como apostador como en distintos Bookmakers donde fue jefe de una casa de apuestas y jefe de trading en operadores como NordicBet y Coolbet. Sus especialidades son el f\u00fatbol y el hockey sobre hielo, aunque busca valor en cualquier deporte.\",\"url\":\"https:\\\/\\\/www.apuestasbono.com\\\/pe\\\/author\\\/nikolaj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Copa Mundial 2026- Apuestas Bono Per\u00fa","description":"Ent\u00e9rate de todo sobre la Copa Mundial 2026: gu\u00edas de selecciones, grupos, calendario, noticias e informaci\u00f3n para tus apuestas deportivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/","og_locale":"es_ES","og_type":"article","og_title":"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas","og_description":"Ent\u00e9rate de todo sobre la Copa Mundial 2026: gu\u00edas de selecciones, grupos, calendario, noticias e informaci\u00f3n para tus apuestas deportivas.","og_url":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/","og_site_name":"Apuestas Bono Per\u00fa","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61561475662418","article_published_time":"2026-05-23T22:38:23+00:00","article_modified_time":"2026-06-11T05:21:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-del-Mundo-scaled.webp","type":"image\/webp"}],"author":"Nikolaj","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nikolaj","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#article","isPartOf":{"@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/"},"author":{"name":"Nikolaj","@id":"https:\/\/www.apuestasbono.com\/pe\/#\/schema\/person\/a7e418560e8162066d2bc2ebccafc84d"},"headline":"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas","datePublished":"2026-05-23T22:38:23+00:00","dateModified":"2026-06-11T05:21:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/"},"wordCount":576,"publisher":{"@id":"https:\/\/www.apuestasbono.com\/pe\/#organization"},"image":{"@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#primaryimage"},"thumbnailUrl":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-del-Mundo-scaled.webp","keywords":["Copa del Mundo 2026"],"articleSection":["Uncategorized"],"inLanguage":"es-PE"},{"@type":"WebPage","@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/","url":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/","name":"Copa Mundial 2026- Apuestas Bono Per\u00fa","isPartOf":{"@id":"https:\/\/www.apuestasbono.com\/pe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#primaryimage"},"image":{"@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#primaryimage"},"thumbnailUrl":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-del-Mundo-scaled.webp","datePublished":"2026-05-23T22:38:23+00:00","dateModified":"2026-06-11T05:21:59+00:00","description":"Ent\u00e9rate de todo sobre la Copa Mundial 2026: gu\u00edas de selecciones, grupos, calendario, noticias e informaci\u00f3n para tus apuestas deportivas.","breadcrumb":{"@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/"]}]},{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#primaryimage","url":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-del-Mundo-scaled.webp","contentUrl":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/05\/Trofeo-de-la-Copa-del-Mundo-scaled.webp","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.apuestasbono.com\/pe\/copa-mundial-2026-calendario-grupos-apuestas-11572\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apuestasbono.com\/pe\/"},{"@type":"ListItem","position":2,"name":"Todo sobre la Copa Mundial 2026: calendario, grupos, an\u00e1lisis y apuestas"}]},{"@type":"WebSite","@id":"https:\/\/www.apuestasbono.com\/pe\/#website","url":"https:\/\/www.apuestasbono.com\/pe\/","name":"Apuestas Bono Per\u00fa","description":"Portal de apuestas deportivas en Per\u00fa con pron\u00f3sticos diarios, an\u00e1lisis de partidos, cuotas actualizadas y comparativas de operadores.","publisher":{"@id":"https:\/\/www.apuestasbono.com\/pe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apuestasbono.com\/pe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Organization","@id":"https:\/\/www.apuestasbono.com\/pe\/#organization","name":"Apuestas Bono Per\u00fa","alternateName":"ApuestasBono Per\u00fa","url":"https:\/\/www.apuestasbono.com\/pe\/","logo":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/www.apuestasbono.com\/pe\/#\/schema\/logo\/image\/","url":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/06\/ApuestasBono-Icono.png","contentUrl":"https:\/\/www.apuestasbono.com\/pe\/wp-content\/uploads\/sites\/5\/2026\/06\/ApuestasBono-Icono.png","width":512,"height":512,"caption":"Apuestas Bono Per\u00fa"},"image":{"@id":"https:\/\/www.apuestasbono.com\/pe\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61561475662418","https:\/\/www.instagram.com\/apuestasbono?igsh=MTg3MTFyajVnbXBsZw=="],"description":"Portal de apuestas deportivas en Per\u00fa con pron\u00f3sticos diarios, an\u00e1lisis de partidos, cuotas actualizadas y comparativas de operadores."},{"@type":"Person","@id":"https:\/\/www.apuestasbono.com\/pe\/#\/schema\/person\/a7e418560e8162066d2bc2ebccafc84d","name":"Nikolaj","image":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/www.apuestasbono.com\/wp-content\/uploads\/2026\/06\/Nikolaj-Juul-Nielsen-96x96.jpg","url":"https:\/\/www.apuestasbono.com\/wp-content\/uploads\/2026\/06\/Nikolaj-Juul-Nielsen-96x96.jpg","contentUrl":"https:\/\/www.apuestasbono.com\/wp-content\/uploads\/2026\/06\/Nikolaj-Juul-Nielsen-96x96.jpg","caption":"Nikolaj"},"description":"\u201cNiko\u201d es de Dinamarca y ha trabajado profesionalmente en el sector de las apuestas deportivas durante m\u00e1s de 25 a\u00f1os. Ha ejercido tanto como apostador como en distintos Bookmakers donde fue jefe de una casa de apuestas y jefe de trading en operadores como NordicBet y Coolbet. Sus especialidades son el f\u00fatbol y el hockey sobre hielo, aunque busca valor en cualquier deporte.","url":"https:\/\/www.apuestasbono.com\/pe\/author\/nikolaj\/"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/posts\/11572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/comments?post=11572"}],"version-history":[{"count":212,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/posts\/11572\/revisions"}],"predecessor-version":[{"id":13012,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/posts\/11572\/revisions\/13012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/media\/11574"}],"wp:attachment":[{"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/media?parent=11572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/categories?post=11572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apuestasbono.com\/pe\/wp-json\/wp\/v2\/tags?post=11572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}